{"id":2901,"date":"2024-08-28T18:58:17","date_gmt":"2024-08-28T21:58:17","guid":{"rendered":"https:\/\/notiamba.com\/?p=2901"},"modified":"2024-08-28T18:58:18","modified_gmt":"2024-08-28T21:58:18","slug":"recuperan-pastizales-pampeanos-del-dique-roggero","status":"publish","type":"post","link":"https:\/\/notiamba.com\/index.php\/2024\/08\/28\/recuperan-pastizales-pampeanos-del-dique-roggero\/","title":{"rendered":"RECUPERAN PASTIZALES PAMPEANOS DEL DIQUE ROGGERO"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Recientemente se inform\u00f3 que gracias a la gesti\u00f3n municipal encabezada por Mariel Fern\u00e1ndez se recuper\u00f3 por v\u00eda legal decenas de hect\u00e1reas de pastizales en el importante espejo de agua que une Merlo con Moreno.<\/h2>\n\n\n\n<p>La Coordinaci\u00f3n General de Guardaparques del Dique Roggero, que contiene aguas del Lago San Fransico y limita los distritos de Merlo y Moreno, comunic\u00f3 la recuperaci\u00f3n de m\u00e1s de 20 hect\u00e1reas\u00a0 de pastizal pampeano.<\/p>\n\n\n\n<p>El \u00c1rea Natural Protegida \u201cDique Roggero\u201d, se destaca por incluir los cuatro ambientes que integran la Regi\u00f3n Pampeana: el bosque, los pastizales, los humedales y el monte.<\/p>\n\n\n\n<p>La Coordinaci\u00f3n General de Guardaparques, a cargo de Jos\u00e9 Luis Barreiro, expres\u00f3: <em>\u201cEstamos recuperando 20 hect\u00e1reas de pastizal pampeano y trabajamos en la ampliaci\u00f3n de senderos que cruzan los cuatro ambientes del \u00c1rea Natural Protegida\u201d.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/notiamba.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-28-at-18.36.26-1024x576.jpeg\" alt=\"\" class=\"wp-image-2903\" srcset=\"https:\/\/notiamba.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-28-at-18.36.26-1024x576.jpeg 1024w, https:\/\/notiamba.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-28-at-18.36.26-300x169.jpeg 300w, https:\/\/notiamba.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-28-at-18.36.26-768x432.jpeg 768w, https:\/\/notiamba.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-28-at-18.36.26-150x84.jpeg 150w, https:\/\/notiamba.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-28-at-18.36.26-696x391.jpeg 696w, https:\/\/notiamba.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-28-at-18.36.26-1068x601.jpeg 1068w, https:\/\/notiamba.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-28-at-18.36.26.jpeg 1236w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>\u201c<em>Seg\u00fan nuestro cronograma estaremos en condiciones de inaugurar el primer tramo de los nuevos senderos hacia fines de septiembre porque todo nuestro equipo de Guardaparques est\u00e1 involucrado en la toma de consciencia y trabaja d\u00eda a d\u00eda contra las consecuencias de la crisis ambiental\u201d,<\/em> se\u00f1al\u00f3 Barreiro.<\/p>\n\n\n\n<p>Adem\u00e1s, se realiz\u00f3 una gran inversi\u00f3n municipal para los guardaparques &nbsp;del \u00c1rea Natural Protegida en <strong>herramientas, motosierras, chipeadoras y equipos de mediano porte<\/strong>.<\/p>\n\n\n\n<p>Asimismo, desde guardaparques de Moreno declararon: <em>\u201cVivimos una \u00e9poca signada por una gran crisis clim\u00e1tica, y por ello tenemos la urgencia de fomentar y conservar los espacios verdes, m\u00e1s a\u00fan en las grandes ciudades, donde la aglomeraci\u00f3n de personas y la demanda habitacional va en aumento<\/em>\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Recientemente se inform\u00f3 que gracias a la gesti\u00f3n municipal encabezada por Mariel Fern\u00e1ndez se recuper\u00f3 por v\u00eda legal decenas de hect\u00e1reas de pastizales en el importante espejo de agua que une Merlo con Moreno. La Coordinaci\u00f3n General de Guardaparques del Dique Roggero, que contiene aguas del Lago San Fransico y limita los distritos de Merlo [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2902,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[674,43,31,675,676],"class_list":{"0":"post-2901","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sociedad-mello","8":"tag-dique-roggero","9":"tag-merlo","10":"tag-moreno","11":"tag-pastizales","12":"tag-recuperacion"},"_links":{"self":[{"href":"https:\/\/notiamba.com\/index.php\/wp-json\/wp\/v2\/posts\/2901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/notiamba.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/notiamba.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/notiamba.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/notiamba.com\/index.php\/wp-json\/wp\/v2\/comments?post=2901"}],"version-history":[{"count":1,"href":"https:\/\/notiamba.com\/index.php\/wp-json\/wp\/v2\/posts\/2901\/revisions"}],"predecessor-version":[{"id":2904,"href":"https:\/\/notiamba.com\/index.php\/wp-json\/wp\/v2\/posts\/2901\/revisions\/2904"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/notiamba.com\/index.php\/wp-json\/wp\/v2\/media\/2902"}],"wp:attachment":[{"href":"https:\/\/notiamba.com\/index.php\/wp-json\/wp\/v2\/media?parent=2901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/notiamba.com\/index.php\/wp-json\/wp\/v2\/categories?post=2901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/notiamba.com\/index.php\/wp-json\/wp\/v2\/tags?post=2901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}